{"id":338,"count":0,"description":"","link":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/","name":"Costi contabilizzati","slug":"costi-contabilizzati","taxonomy":"categoria_albo_pretorio","parent":335,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Costi contabilizzati Archivi - Consorzio di Bonifica 4 Caltanissetta<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Costi contabilizzati Archivi - Consorzio di Bonifica 4 Caltanissetta\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica 4 Caltanissetta\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website\",\"url\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/\",\"name\":\"Consorzio di Bonifica 4 Caltanissetta\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/#webpage\",\"url\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/\",\"name\":\"Costi contabilizzati Archivi - Consorzio di Bonifica 4 Caltanissetta\",\"isPartOf\":{\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Servizi erogati\",\"item\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/servizi-erogati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Costi contabilizzati\"}]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Costi contabilizzati Archivi - Consorzio di Bonifica 4 Caltanissetta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/","og_locale":"it_IT","og_type":"article","og_title":"Costi contabilizzati Archivi - Consorzio di Bonifica 4 Caltanissetta","og_url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/","og_site_name":"Consorzio di Bonifica 4 Caltanissetta","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website","url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/","name":"Consorzio di Bonifica 4 Caltanissetta","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"CollectionPage","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/#webpage","url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/","name":"Costi contabilizzati Archivi - Consorzio di Bonifica 4 Caltanissetta","isPartOf":{"@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website"},"breadcrumb":{"@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/costi-contabilizzati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Servizi erogati","item":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/servizi-erogati\/"},{"@type":"ListItem","position":2,"name":"Costi contabilizzati"}]}]}},"_links":{"self":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/categoria_albo_pretorio\/338"}],"collection":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/categoria_albo_pretorio"}],"about":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/taxonomies\/categoria_albo_pretorio"}],"up":[{"embeddable":true,"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/categoria_albo_pretorio\/335"}],"wp:post_type":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/albo_pretorio?categoria_albo_pretorio=338"},{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/amm_trasparente?categoria_albo_pretorio=338"},{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/archiv_albo_pretorio?categoria_albo_pretorio=338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}