{"id":305,"count":1,"description":"","link":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/","name":"Documento dell'OIV di validazione della Relazione sulla Performance","slug":"documento-delloiv-di-validazione-della-relazione-sulla-performance","taxonomy":"categoria_albo_pretorio","parent":301,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Documento dell&#039;OIV di validazione della Relazione sulla Performance Archivi - Consorzio di Bonifica 4 Caltanissetta<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Documento dell&#039;OIV di validazione della Relazione sulla Performance Archivi - Consorzio di Bonifica 4 Caltanissetta\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica 4 Caltanissetta\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website\",\"url\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/\",\"name\":\"Consorzio di Bonifica 4 Caltanissetta\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/#webpage\",\"url\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/\",\"name\":\"Documento dell'OIV di validazione della Relazione sulla Performance Archivi - Consorzio di Bonifica 4 Caltanissetta\",\"isPartOf\":{\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Performance\",\"item\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/performance\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documento dell'OIV di validazione della Relazione sulla Performance\"}]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Documento dell'OIV di validazione della Relazione sulla Performance Archivi - Consorzio di Bonifica 4 Caltanissetta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/","og_locale":"it_IT","og_type":"article","og_title":"Documento dell'OIV di validazione della Relazione sulla Performance Archivi - Consorzio di Bonifica 4 Caltanissetta","og_url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/","og_site_name":"Consorzio di Bonifica 4 Caltanissetta","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website","url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/","name":"Consorzio di Bonifica 4 Caltanissetta","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"CollectionPage","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/#webpage","url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/","name":"Documento dell'OIV di validazione della Relazione sulla Performance Archivi - Consorzio di Bonifica 4 Caltanissetta","isPartOf":{"@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website"},"breadcrumb":{"@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/documento-delloiv-di-validazione-della-relazione-sulla-performance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Performance","item":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/categoria_albo_pretorio\/performance\/"},{"@type":"ListItem","position":2,"name":"Documento dell'OIV di validazione della Relazione sulla Performance"}]}]}},"_links":{"self":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/categoria_albo_pretorio\/305"}],"collection":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/categoria_albo_pretorio"}],"about":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/taxonomies\/categoria_albo_pretorio"}],"up":[{"embeddable":true,"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/categoria_albo_pretorio\/301"}],"wp:post_type":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/albo_pretorio?categoria_albo_pretorio=305"},{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/amm_trasparente?categoria_albo_pretorio=305"},{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/archiv_albo_pretorio?categoria_albo_pretorio=305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}