{"id":29356,"date":"2025-06-19T11:51:03","date_gmt":"2025-06-19T09:51:03","guid":{"rendered":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/?post_type=albo_pretorio&#038;p=29356"},"modified":"2025-06-19T11:51:07","modified_gmt":"2025-06-19T09:51:07","slug":"bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione","status":"publish","type":"amm_trasparente","link":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/","title":{"rendered":"Bilancio di previsione per l&#8217;esercizio finanziario 2025 e bilancio pluriennale 2026-2027 &#8211; Approvazione"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","categoria_albo_pretorio":[316,317],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Bilancio di previsione per l&#039;esercizio finanziario 2025 e bilancio pluriennale 2026-2027 - Approvazione - Consorzio di Bonifica 4 Caltanissetta<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Bilancio di previsione per l&#039;esercizio finanziario 2025 e bilancio pluriennale 2026-2027 - Approvazione - Consorzio di Bonifica 4 Caltanissetta\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica 4 Caltanissetta\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-06-19T09:51:07+00:00\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website\",\"url\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/\",\"name\":\"Consorzio di Bonifica 4 Caltanissetta\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/#webpage\",\"url\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/\",\"name\":\"Bilancio di previsione per l'esercizio finanziario 2025 e bilancio pluriennale 2026-2027 - Approvazione - Consorzio di Bonifica 4 Caltanissetta\",\"isPartOf\":{\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website\"},\"datePublished\":\"2025-06-19T09:51:03+00:00\",\"dateModified\":\"2025-06-19T09:51:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Albo pretorio\",\"item\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bilancio di previsione per l&#8217;esercizio finanziario 2025 e bilancio pluriennale 2026-2027 &#8211; Approvazione\"}]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bilancio di previsione per l'esercizio finanziario 2025 e bilancio pluriennale 2026-2027 - Approvazione - Consorzio di Bonifica 4 Caltanissetta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/","og_locale":"it_IT","og_type":"article","og_title":"Bilancio di previsione per l'esercizio finanziario 2025 e bilancio pluriennale 2026-2027 - Approvazione - Consorzio di Bonifica 4 Caltanissetta","og_url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/","og_site_name":"Consorzio di Bonifica 4 Caltanissetta","article_modified_time":"2025-06-19T09:51:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website","url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/","name":"Consorzio di Bonifica 4 Caltanissetta","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/#webpage","url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/","name":"Bilancio di previsione per l'esercizio finanziario 2025 e bilancio pluriennale 2026-2027 - Approvazione - Consorzio di Bonifica 4 Caltanissetta","isPartOf":{"@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website"},"datePublished":"2025-06-19T09:51:03+00:00","dateModified":"2025-06-19T09:51:07+00:00","breadcrumb":{"@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/bilancio-di-previsione-per-lesercizio-finanziario-2025-e-bilancio-pluriennale-2026-2027-approvazione\/29356\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Albo pretorio","item":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/albo_pretorio\/"},{"@type":"ListItem","position":2,"name":"Bilancio di previsione per l&#8217;esercizio finanziario 2025 e bilancio pluriennale 2026-2027 &#8211; Approvazione"}]}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"large-thumb":false,"mansory-thumb":false,"single-alignfull-thumb":false,"sow-carousel-default":false},"uagb_author_info":{"display_name":"Simone","author_link":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/amm_trasparente\/29356"}],"collection":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/amm_trasparente"}],"about":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/types\/amm_trasparente"}],"wp:attachment":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/media?parent=29356"}],"wp:term":[{"taxonomy":"categoria_albo_pretorio","embeddable":true,"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/categoria_albo_pretorio?post=29356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}