{"id":23882,"date":"2021-07-19T13:09:58","date_gmt":"2021-07-19T11:09:58","guid":{"rendered":"http:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/"},"modified":"2021-10-04T11:19:43","modified_gmt":"2021-10-04T09:19:43","slug":"attestazione-oiv-2021","status":"publish","type":"amm_trasparente","link":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/23882\/","title":{"rendered":"Attestazione OIV 2021"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","categoria_albo_pretorio":[276,359],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Attestazione OIV 2021 - Consorzio di Bonifica 4 Caltanissetta<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Attestazione OIV 2021 - Consorzio di Bonifica 4 Caltanissetta\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica 4 Caltanissetta\" \/>\r\n<meta property=\"article:modified_time\" content=\"2021-10-04T09:19:43+00:00\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website\",\"url\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/\",\"name\":\"Consorzio di Bonifica 4 Caltanissetta\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/#webpage\",\"url\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/\",\"name\":\"Attestazione OIV 2021 - Consorzio di Bonifica 4 Caltanissetta\",\"isPartOf\":{\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website\"},\"datePublished\":\"2021-07-19T11:09:58+00:00\",\"dateModified\":\"2021-10-04T09:19:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Attestazione OIV 2021\"}]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attestazione OIV 2021 - Consorzio di Bonifica 4 Caltanissetta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/","og_locale":"it_IT","og_type":"article","og_title":"Attestazione OIV 2021 - Consorzio di Bonifica 4 Caltanissetta","og_url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/","og_site_name":"Consorzio di Bonifica 4 Caltanissetta","article_modified_time":"2021-10-04T09:19:43+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website","url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/","name":"Consorzio di Bonifica 4 Caltanissetta","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/#webpage","url":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/","name":"Attestazione OIV 2021 - Consorzio di Bonifica 4 Caltanissetta","isPartOf":{"@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/#website"},"datePublished":"2021-07-19T11:09:58+00:00","dateModified":"2021-10-04T09:19:43+00:00","breadcrumb":{"@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/amm_trasparente\/attestazione-oiv-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Attestazione OIV 2021"}]}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"large-thumb":false,"mansory-thumb":false,"single-alignfull-thumb":false,"sow-carousel-default":false},"uagb_author_info":{"display_name":"consorzio_usr","author_link":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/amm_trasparente\/23882"}],"collection":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/amm_trasparente"}],"about":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/types\/amm_trasparente"}],"wp:attachment":[{"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/media?parent=23882"}],"wp:term":[{"taxonomy":"categoria_albo_pretorio","embeddable":true,"href":"https:\/\/www.consorziobonifica4caltanissetta.it\/cbc\/wp-json\/wp\/v2\/categoria_albo_pretorio?post=23882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}